{"id":143984,"date":"2022-12-05T08:18:07","date_gmt":"2022-12-05T11:18:07","guid":{"rendered":"http:\/\/www.blogdothame.blog.br\/v1\/?p=143984"},"modified":"2022-12-05T09:33:10","modified_gmt":"2022-12-05T12:33:10","slug":"secretaria-de-saude-confirma-casos-de-zika-e-chikungunya-e-alerta-para-risco-de-surto-em-ilheus","status":"publish","type":"post","link":"https:\/\/www.blogdothame.blog.br\/v1\/2022\/12\/05\/secretaria-de-saude-confirma-casos-de-zika-e-chikungunya-e-alerta-para-risco-de-surto-em-ilheus\/","title":{"rendered":"Secretaria de Sa\u00fade confirma casos de zika e chikungunya e alerta para risco de surto em Ilh\u00e9us"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"alignright size-medium wp-image-143985\" src=\"http:\/\/www.blogdothame.blog.br\/v1\/wp-content\/uploads\/2022\/12\/zika-300x208.jpg\" alt=\"\" width=\"300\" height=\"208\" srcset=\"https:\/\/www.blogdothame.blog.br\/v1\/wp-content\/uploads\/2022\/12\/zika-300x208.jpg 300w, https:\/\/www.blogdothame.blog.br\/v1\/wp-content\/uploads\/2022\/12\/zika.jpg 650w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>A Prefeitura de Ilh\u00e9us confirmou 38 casos de arboviroses, dos quais 25 foram de zika e 13 de chikungunya. Conforme a Secretaria de Sa\u00fade (Sesau), outros 1.106 casos se enquadram como suspeitos e aguardam an\u00e1lise realizada pelo Laborat\u00f3rio Central de Sa\u00fade P\u00fablica da Bahia (LACEN). O boletim foi divulgado pelo setor de Vigil\u00e2ncia Epidemiol\u00f3gica e de Endemias (VIEP) na \u00faltima segunda-feira (28).<\/p>\n<p>A Sesau explica que a chegada do fim do ano, tradicionalmente, aumenta o n\u00famero de focos do Aedes aegypti, transmissor da dengue, zika, chikungunya e febre amarela. O VIEP aponta algumas localidades que registraram aumento do n\u00famero de casos e est\u00e3o em situa\u00e7\u00e3o de alerta, principalmente os bairros da Conquista, onde foram notificados 128 casos; seguido do Nelson Costa, com 115 casos; e do Nossa Senhora da Vit\u00f3ria\/Condom\u00ednio Sol e Mar, que possui 107 casos suspeitos.<\/p>\n<p><!--more--><\/p>\n<p>Os bairros Hernani S\u00e1, Malhado, Pontal, S\u00e3o Francisco e Teot\u00f4nio Vilela somam 304 casos sob investiga\u00e7\u00e3o. A Sesau explica que os agentes de combate \u00e0s endemias realizam um trabalho educativo para alertar a popula\u00e7\u00e3o sobre a import\u00e2ncia de verificar qualquer reservat\u00f3rio que possa servir de criadouro para o mosquito.<\/p>\n<p>Os mun\u00edcipes devem cobrir tanques e ton\u00e9is, evitando o ac\u00famulo de garrafas, copos descart\u00e1veis, latas, pneus, dentre outros objetos que ficam a c\u00e9u aberto com \u00e1gua parada. A comunidade tem papel central na preven\u00e7\u00e3o das doen\u00e7as.<\/p>\n<p>\u201cSeja um cidad\u00e3o cinco estrelas e tire cinco minutos do seu tempo para verificar sua casa. N\u00e3o vamos deixar o mosquito nos vencer\u201d, frisou Jailma Nascimento, diretora do VIEP.<\/p>\n<p>Saiba onde procurar atendimento &#8211;\u00a0A UPA da Esperan\u00e7a e o PA da Zona Sul s\u00e3o refer\u00eancia para os casos no munic\u00edpio.<\/p>\n<p>Disque-dengue \u2013\u00a0A popula\u00e7\u00e3o pode efetuar den\u00fancias de poss\u00edveis criadouros do mosquito em terrenos baldios, casas abandonadas e \u00e1reas mais cr\u00edticas, atrav\u00e9s do n\u00famero (73) 3231-4519. O atendimento funciona de segunda a sexta-feira, das 8h \u00e0s 17h.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Ilh\u00e9us confirmou 38 casos de arboviroses, dos quais 25 foram de zika e 13 de chikungunya. Conforme a Secretaria de Sa\u00fade (Sesau), outros 1.106 casos se enquadram como suspeitos e aguardam an\u00e1lise realizada pelo Laborat\u00f3rio Central de Sa\u00fade P\u00fablica da Bahia (LACEN). O boletim foi divulgado pelo setor de Vigil\u00e2ncia Epidemiol\u00f3gica e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":143985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[33434],"tags":[218,6225,14635],"_links":{"self":[{"href":"https:\/\/www.blogdothame.blog.br\/v1\/wp-json\/wp\/v2\/posts\/143984"}],"collection":[{"href":"https:\/\/www.blogdothame.blog.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.blogdothame.blog.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.blogdothame.blog.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blogdothame.blog.br\/v1\/wp-json\/wp\/v2\/comments?post=143984"}],"version-history":[{"count":1,"href":"https:\/\/www.blogdothame.blog.br\/v1\/wp-json\/wp\/v2\/posts\/143984\/revisions"}],"predecessor-version":[{"id":143986,"href":"https:\/\/www.blogdothame.blog.br\/v1\/wp-json\/wp\/v2\/posts\/143984\/revisions\/143986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.blogdothame.blog.br\/v1\/wp-json\/wp\/v2\/media\/143985"}],"wp:attachment":[{"href":"https:\/\/www.blogdothame.blog.br\/v1\/wp-json\/wp\/v2\/media?parent=143984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.blogdothame.blog.br\/v1\/wp-json\/wp\/v2\/categories?post=143984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.blogdothame.blog.br\/v1\/wp-json\/wp\/v2\/tags?post=143984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}